{"id":1843,"date":"2021-08-03T09:49:08","date_gmt":"2021-08-03T07:49:08","guid":{"rendered":"https:\/\/estatestudio.com\/?page_id=1843"},"modified":"2022-07-04T09:38:33","modified_gmt":"2022-07-04T07:38:33","slug":"selectionnez-votre-template","status":"publish","type":"page","link":"https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/","title":{"rendered":"S\u00e9lectionnez votre template"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1843\" class=\"elementor elementor-1843\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f9b180 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"5f9b180\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0950bbc\" data-id=\"0950bbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d04aed elementor-widget elementor-widget-text-editor\" data-id=\"1d04aed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCr\u00e9ez votre vid\u00e9o\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e46c257 elementor-widget elementor-widget-text-editor\" data-id=\"e46c257\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quelques minutes pour choisir votre mod\u00e8le, ajouter vos photos, vos informations et votre vid\u00e9o immobili\u00e8re est pr\u00eate\u00a0!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a77a39 elementor-widget elementor-widget-html\" data-id=\"6a77a39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\ndocument.addEventListener('DOMContentLoaded', function() {\njQuery(function($){\n$('.showme').click(function(){\n$(this).closest('.elementor-section').next().slideToggle();\n$(this).toggleClass('opened');\n});\n$('.closebutton').click(function(){\n$(this).closest('.elementor-section').prev().find('.showme').click();\n});\n});\n});\n<\/script>\n<style>\n.showme a, .showme svg, .showme i , .showme img, .closebutton a, .closebutton i, .closebutton img{\n        cursor: pointer;\n        -webkit-transition: transform 0.34s ease;\ntransition : transform 0.34s ease;\n    }\n.opened i , .opened img,.opened svg{\n        transform: rotate(90deg);\n    }\n<\/style>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e78b79 showme elementor-widget elementor-widget-text-editor\" data-id=\"3e78b79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tS\u00e9lectionnez <span style=\"color: #d62e87;\">votre r\u00e9seau<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9ba7a2 elementor-widget elementor-widget-shortcode\" data-id=\"d9ba7a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"><div class=\"img-themes\" style=\"width:100%;\"><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-0 img-agency imageframe-1 elementor-column\" id=\"agency-CapiFrance\"><img decoding=\"async\" title=\"CapiFrance\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/CapiFrance.jpg\" class=\"img-responsive\" id=\"agency-0\" onclick=\"show_agency_templates(2771,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-1 img-agency imageframe-2 elementor-column\" id=\"agency-Century21\"><img decoding=\"async\" title=\"Century21\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2021\/08\/Century-21-logo.jpg\" class=\"img-responsive\" id=\"agency-1\" onclick=\"show_agency_templates(2061,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-2 img-agency imageframe-3 elementor-column\" id=\"agency-ColdwellBanker\"><img decoding=\"async\" title=\"ColdwellBanker\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2020\/09\/Coldwell-Banker-Logo-1.jpg\" class=\"img-responsive\" id=\"agency-2\" onclick=\"show_agency_templates(177,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-3 img-agency imageframe-4 elementor-column\" id=\"agency-Era\"><img decoding=\"async\" title=\"Era\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2020\/09\/EraFrance_251x106.jpg\" class=\"img-responsive\" id=\"agency-3\" onclick=\"show_agency_templates(186,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-4 img-agency imageframe-5 elementor-column\" id=\"agency-Fnaim\"><img decoding=\"async\" title=\"Fnaim\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/Fnaim.jpg\" class=\"img-responsive\" id=\"agency-4\" onclick=\"show_agency_templates(2679,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-5 img-agency imageframe-6 elementor-column\" id=\"agency-Foncia\"><img decoding=\"async\" title=\"Foncia\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/Foncia.jpg\" class=\"img-responsive\" id=\"agency-5\" onclick=\"show_agency_templates(2894,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-6 img-agency imageframe-7 elementor-column\" id=\"agency-GuyHoquet\"><img decoding=\"async\" title=\"GuyHoquet\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/guyhoquet.jpg\" class=\"img-responsive\" id=\"agency-6\" onclick=\"show_agency_templates(2717,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-7 img-agency imageframe-8 elementor-column\" id=\"agency-HumanImmobilier\"><img decoding=\"async\" title=\"HumanImmobilier\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/Human.jpg\" class=\"img-responsive\" id=\"agency-7\" onclick=\"show_agency_templates(2898,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-8 img-agency imageframe-9 elementor-column\" id=\"agency-iad\"><img decoding=\"async\" title=\"iad\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/iad.jpg\" class=\"img-responsive\" id=\"agency-8\" onclick=\"show_agency_templates(2681,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-9 img-agency imageframe-10 elementor-column\" id=\"agency-lAdresse\"><img decoding=\"async\" title=\"lAdresse\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/lAdresse.jpg\" class=\"img-responsive\" id=\"agency-9\" onclick=\"show_agency_templates(2904,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-10 img-agency imageframe-11 elementor-column\" id=\"agency-laforet\"><img decoding=\"async\" title=\"laforet\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/Laforet-V2.jpg\" class=\"img-responsive\" id=\"agency-10\" onclick=\"show_agency_templates(2683,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-11 img-agency imageframe-12 elementor-column\" id=\"agency-LaFourmiImmo\"><img decoding=\"async\" title=\"LaFourmiImmo\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/LaFourmi.jpg\" class=\"img-responsive\" id=\"agency-11\" onclick=\"show_agency_templates(2773,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-12 img-agency imageframe-13 elementor-column\" id=\"agency-Nexity\"><img decoding=\"async\" title=\"Nexity\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/Nexity.jpg\" class=\"img-responsive\" id=\"agency-12\" onclick=\"show_agency_templates(2902,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-13 img-agency imageframe-14 elementor-column\" id=\"agency-Orpi\"><img decoding=\"async\" title=\"Orpi\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/Orpi.jpg\" class=\"img-responsive\" id=\"agency-13\" onclick=\"show_agency_templates(2685,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-14 img-agency imageframe-15 elementor-column\" id=\"agency-ProprietesPrivees\"><img decoding=\"async\" title=\"ProprietesPrivees\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/Proprietes-privees.jpg\" class=\"img-responsive\" id=\"agency-14\" onclick=\"show_agency_templates(2908,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-15 img-agency imageframe-16 elementor-column\" id=\"agency-Remax\"><img decoding=\"async\" title=\"Remax\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2021\/08\/ReMax-Logo.jpg\" class=\"img-responsive\" id=\"agency-15\" onclick=\"show_agency_templates(2060,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-16 img-agency imageframe-17 elementor-column\" id=\"agency-Safti\"><img decoding=\"async\" title=\"Safti\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/Safti.jpg\" class=\"img-responsive\" id=\"agency-16\" onclick=\"show_agency_templates(2906,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-17 img-agency imageframe-18 elementor-column\" id=\"agency-Sothebys\"><img decoding=\"async\" title=\"Sothebys\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2020\/11\/Sothebys-logo.jpg\" class=\"img-responsive\" id=\"agency-17\" onclick=\"show_agency_templates(220,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-18 img-agency imageframe-19 elementor-column\" id=\"agency-SquareHabitat\"><img decoding=\"async\" title=\"SquareHabitat\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/SquareHabitat.jpg\" class=\"img-responsive\" id=\"agency-18\" onclick=\"show_agency_templates(2900,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><div class=\"logos-agencies-box-choice\"><div class=\"fusion-builder-nested-column-19 img-agency imageframe-20 elementor-column\" id=\"agency-StephanePlaza\"><img decoding=\"async\" title=\"StephanePlaza\" src=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/01\/StephanePlaza.jpg\" class=\"img-responsive\" id=\"agency-19\" onclick=\"show_agency_templates(2896,'\u00c9DITER CE MOD\u00c8LE');\"><\/div><\/div><\/div><\/div>\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ebff4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ebff4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4dbb0df\" data-id=\"4dbb0df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8994975 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8994975\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-question-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Le r\u00e9seau que vous cherchez  n'est pas disponible ? <a href=\"\/contact\/\" style=\"font-weight:700;color: var( --e-global-color-primary )\">Contactez-nous<\/a> pour l'ajouter \u00e0 EstateStudio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7269074 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7269074\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2236229\" data-id=\"2236229\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cad6f92 elementor-widget elementor-widget-shortcode\" data-id=\"cad6f92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"templates-for-an-agency elementor-element\"><\/div>\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23297d2 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"23297d2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c1cb7b9\" data-id=\"c1cb7b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08a10f8 elementor-widget elementor-widget-text-editor\" data-id=\"08a10f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>OU<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e959e1c elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"5e959e1c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d8c8f41\" data-id=\"d8c8f41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b970161 elementor-widget elementor-widget-text-editor\" data-id=\"3b970161\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPersonnalisez un mod\u00e8le <span style=\"color: #d62e87;\">\u00e0 vos couleurs<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8038df7 elementor-widget elementor-widget-shortcode\" data-id=\"8038df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t<div class=\"elementor-element\" id=\"\"><div class=\"elementor-container\"><div style=\"width:100%;\"><div class=\"display-one-template-box-choice\"><div class=\"elementor-column elementor-inner-column elementor-element bg-grey-gradient\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-widget\" data-element_type=\"widget\"><div class=\"elementor-widget-container\"><div class=\"elementor-row template-one-custom hover-cursor-pointer\" id=\"FRCTOpener02-template-one-custom\" style=\"position:relative;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Opener02-1-width680.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"><div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div><script>$(\"#FRCTOpener02-template-one-custom\").click(function() {$(\"#FRCTOpener02-template-one-custom\").html(' <video id=\"video-FRCTOpener02\" poster=\"\/wp-content\/uploads\/src\/img\/FR-CT-Opener02-1.jpg\" controls> <source src=\"https:\/\/cdn.jwplayer.com\/videos\/q7IwbQDm-ovXvHCqB.mp4\" type=\"video\/mp4\"> <\/video> <script> $(document).ready(function(){ var videoFRCTOpener02 = $(\"#video-FRCTOpener02\").get(0); videoFRCTOpener02.play(); videoFRCTOpener02.addEventListener(\"ended\", function(){ var imgContentSimVideo = `<img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Opener02-1.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"> <div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div>`; $(\"#FRCTOpener02-template-one-custom\").html(imgContentSimVideo); }); }); <\\\/script>');});<\/script><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"fas fa-stopwatch picto-fontawesome-infos-template\"><\/i>30 sec.<\/div><\/div><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"far fa-images picto-fontawesome-infos-template\"><\/i>7<\/div><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element\" data-element_type=\"column\" style=\"text-align:center;\"><a class=\"button-choose-template-agency\" target=\"_self\" href=\"https:\/\/estatestudio.com\/fr\/produit\/fr-ct-opener02\/\">\u00c9DITER CE MOD\u00c8LE <i class=\"fa-angle-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-title-short-description\" data-element_type=\"column\">Estate Sharing<\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-short-description\" data-element_type=\"column\">Un mod\u00e8le de vid\u00e9o rapide \u00e0 personnaliser\u00a0 pour pouvoir la partager sur les r\u00e9seaux sociaux. Ins\u00e9rez votre logo, ses points forts, 7 photos pour mettre en valeur le bien et vous avez cr\u00e9\u00e9 votre vid\u00e9o immobili\u00e8re !<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"display-one-template-box-choice\"><div class=\"elementor-column elementor-inner-column elementor-element bg-grey-gradient\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-widget\" data-element_type=\"widget\"><div class=\"elementor-widget-container\"><div class=\"elementor-row template-one-custom hover-cursor-pointer\" id=\"FRCTOpener03-template-one-custom\" style=\"position:relative;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Opener03-1-width680.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"><div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div><script>$(\"#FRCTOpener03-template-one-custom\").click(function() {$(\"#FRCTOpener03-template-one-custom\").html(' <video id=\"video-FRCTOpener03\" poster=\"\/wp-content\/uploads\/src\/img\/FR-CT-Opener03-1.jpg\" controls> <source src=\"https:\/\/cdn.jwplayer.com\/videos\/nOTDq9um-ovXvHCqB.mp4\" type=\"video\/mp4\"> <\/video> <script> $(document).ready(function(){ var videoFRCTOpener03 = $(\"#video-FRCTOpener03\").get(0); videoFRCTOpener03.play(); videoFRCTOpener03.addEventListener(\"ended\", function(){ var imgContentSimVideo = `<img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Opener03-1.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"> <div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div>`; $(\"#FRCTOpener03-template-one-custom\").html(imgContentSimVideo); }); }); <\\\/script>');});<\/script><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"fas fa-stopwatch picto-fontawesome-infos-template\"><\/i>30 sec.<\/div><\/div><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"far fa-images picto-fontawesome-infos-template\"><\/i>9<\/div><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element\" data-element_type=\"column\" style=\"text-align:center;\"><a class=\"button-choose-template-agency\" target=\"_self\" href=\"https:\/\/estatestudio.com\/fr\/produit\/fr-ct-opener03\/\">\u00c9DITER CE MOD\u00c8LE <i class=\"fa-angle-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-title-short-description\" data-element_type=\"column\">Estate Essential<\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-short-description\" data-element_type=\"column\">Animez votre annonce immobili\u00e8re avec ce mod\u00e8le de vid\u00e9o en allant \u00e0 l'essentiel : mise en valeur de votre bien avec de superbes photos, mention de ses points forts, vos informations de contact. Votre vid\u00e9o est pr\u00eate !<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"display-one-template-box-choice\"><div class=\"elementor-column elementor-inner-column elementor-element bg-grey-gradient\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-widget\" data-element_type=\"widget\"><div class=\"elementor-widget-container\"><div class=\"elementor-row template-one-custom hover-cursor-pointer\" id=\"FRCSSlideshow01-template-one-custom\" style=\"position:relative;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CS-Slideshow01-1-width680.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"><div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div><script>$(\"#FRCSSlideshow01-template-one-custom\").click(function() {$(\"#FRCSSlideshow01-template-one-custom\").html(' <video id=\"video-FRCSSlideshow01\" poster=\"\/wp-content\/uploads\/src\/img\/FR-CS-Slideshow01-1.jpg\" controls> <source src=\"https:\/\/cdn.jwplayer.com\/videos\/g1UF8xWB-ovXvHCqB.mp4\" type=\"video\/mp4\"> <\/video> <script> $(document).ready(function(){ var videoFRCSSlideshow01 = $(\"#video-FRCSSlideshow01\").get(0); videoFRCSSlideshow01.play(); videoFRCSSlideshow01.addEventListener(\"ended\", function(){ var imgContentSimVideo = `<img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CS-Slideshow01-1.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"> <div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div>`; $(\"#FRCSSlideshow01-template-one-custom\").html(imgContentSimVideo); }); }); <\\\/script>');});<\/script><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"fas fa-stopwatch picto-fontawesome-infos-template\"><\/i>30 sec.<\/div><\/div><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"far fa-images picto-fontawesome-infos-template\"><\/i>7<\/div><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element\" data-element_type=\"column\" style=\"text-align:center;\"><a class=\"button-choose-template-agency\" target=\"_self\" href=\"https:\/\/estatestudio.com\/fr\/produit\/fr-cs-slideshow01\/\">\u00c9DITER CE MOD\u00c8LE <i class=\"fa-angle-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-title-short-description\" data-element_type=\"column\">Estate Plus<\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-short-description\" data-element_type=\"column\">Pr\u00e9sentez rapidement diff\u00e9rentes pi\u00e8ces du bien \u00e0 vendre gr\u00e2ce \u00e0 ce mod\u00e8le de vid\u00e9o qui permet de faire d\u00e9filer chaque photo tout en ayant un aper\u00e7u sur les 3 suivantes.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"display-one-template-box-choice\"><div class=\"elementor-column elementor-inner-column elementor-element bg-grey-gradient\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-widget\" data-element_type=\"widget\"><div class=\"elementor-widget-container\"><div class=\"elementor-row template-one-custom hover-cursor-pointer\" id=\"FRCTSlideshow01-template-one-custom\" style=\"position:relative;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Slideshow01-1-width680.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"><div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div><script>$(\"#FRCTSlideshow01-template-one-custom\").click(function() {$(\"#FRCTSlideshow01-template-one-custom\").html(' <video id=\"video-FRCTSlideshow01\" poster=\"\/wp-content\/uploads\/src\/img\/FR-CT-Slideshow01-1.jpg\" controls> <source src=\"https:\/\/cdn.jwplayer.com\/videos\/EPrTwCKC-ovXvHCqB.mp4\" type=\"video\/mp4\"> <\/video> <script> $(document).ready(function(){ var videoFRCTSlideshow01 = $(\"#video-FRCTSlideshow01\").get(0); videoFRCTSlideshow01.play(); videoFRCTSlideshow01.addEventListener(\"ended\", function(){ var imgContentSimVideo = `<img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Slideshow01-1.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"> <div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div>`; $(\"#FRCTSlideshow01-template-one-custom\").html(imgContentSimVideo); }); }); <\\\/script>');});<\/script><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"fas fa-stopwatch picto-fontawesome-infos-template\"><\/i>30 sec.<\/div><\/div><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"far fa-images picto-fontawesome-infos-template\"><\/i>7<\/div><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element\" data-element_type=\"column\" style=\"text-align:center;\"><a class=\"button-choose-template-agency\" target=\"_self\" href=\"https:\/\/estatestudio.com\/fr\/produit\/fr-ct-slideshow01\/\">\u00c9DITER CE MOD\u00c8LE <i class=\"fa-angle-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-title-short-description\" data-element_type=\"column\">Estate Plus Agent<\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-short-description\" data-element_type=\"column\">Pr\u00e9sentez rapidement diff\u00e9rentes pi\u00e8ces du bien \u00e0 vendre gr\u00e2ce \u00e0 ce mod\u00e8le de vid\u00e9o qui permet de faire d\u00e9filer chaque photo tout en ayant un aper\u00e7u sur les 3 suivantes.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"display-one-template-box-choice\"><div class=\"elementor-column elementor-inner-column elementor-element bg-grey-gradient\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-widget\" data-element_type=\"widget\"><div class=\"elementor-widget-container\"><div class=\"elementor-row template-one-custom hover-cursor-pointer\" id=\"FRCSSlideshow02-template-one-custom\" style=\"position:relative;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CS-Slideshow02-1-width680.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"><div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div><script>$(\"#FRCSSlideshow02-template-one-custom\").click(function() {$(\"#FRCSSlideshow02-template-one-custom\").html(' <video id=\"video-FRCSSlideshow02\" poster=\"\/wp-content\/uploads\/src\/img\/FR-CS-Slideshow02-1.jpg\" controls> <source src=\"https:\/\/cdn.jwplayer.com\/videos\/ILPChels-ovXvHCqB.mp4\" type=\"video\/mp4\"> <\/video> <script> $(document).ready(function(){ var videoFRCSSlideshow02 = $(\"#video-FRCSSlideshow02\").get(0); videoFRCSSlideshow02.play(); videoFRCSSlideshow02.addEventListener(\"ended\", function(){ var imgContentSimVideo = `<img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CS-Slideshow02-1.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"> <div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div>`; $(\"#FRCSSlideshow02-template-one-custom\").html(imgContentSimVideo); }); }); <\\\/script>');});<\/script><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"fas fa-stopwatch picto-fontawesome-infos-template\"><\/i>30 sec.<\/div><\/div><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"far fa-images picto-fontawesome-infos-template\"><\/i>9<\/div><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element\" data-element_type=\"column\" style=\"text-align:center;\"><a class=\"button-choose-template-agency\" target=\"_self\" href=\"https:\/\/estatestudio.com\/fr\/produit\/fr-cs-slideshow02\/\">\u00c9DITER CE MOD\u00c8LE <i class=\"fa-angle-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-title-short-description\" data-element_type=\"column\">Estate Large<\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-short-description\" data-element_type=\"column\">Plan large pour promouvoir les espaces de vie de votre annonce immobili\u00e8re avec ce mod\u00e8le de vid\u00e9o qui fait d\u00e9filer les photos dans un format proche du cin\u00e9ma.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"display-one-template-box-choice\"><div class=\"elementor-column elementor-inner-column elementor-element bg-grey-gradient\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-widget\" data-element_type=\"widget\"><div class=\"elementor-widget-container\"><div class=\"elementor-row template-one-custom hover-cursor-pointer\" id=\"FRCTSlideshow02-template-one-custom\" style=\"position:relative;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Slideshow02-1-width680.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"><div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div><script>$(\"#FRCTSlideshow02-template-one-custom\").click(function() {$(\"#FRCTSlideshow02-template-one-custom\").html(' <video id=\"video-FRCTSlideshow02\" poster=\"\/wp-content\/uploads\/src\/img\/FR-CT-Slideshow02-1.jpg\" controls> <source src=\"https:\/\/cdn.jwplayer.com\/videos\/97vmG9fQ-ovXvHCqB.mp4\" type=\"video\/mp4\"> <\/video> <script> $(document).ready(function(){ var videoFRCTSlideshow02 = $(\"#video-FRCTSlideshow02\").get(0); videoFRCTSlideshow02.play(); videoFRCTSlideshow02.addEventListener(\"ended\", function(){ var imgContentSimVideo = `<img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Slideshow02-1.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"> <div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div>`; $(\"#FRCTSlideshow02-template-one-custom\").html(imgContentSimVideo); }); }); <\\\/script>');});<\/script><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"fas fa-stopwatch picto-fontawesome-infos-template\"><\/i>30 sec.<\/div><\/div><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"far fa-images picto-fontawesome-infos-template\"><\/i>9<\/div><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element\" data-element_type=\"column\" style=\"text-align:center;\"><a class=\"button-choose-template-agency\" target=\"_self\" href=\"https:\/\/estatestudio.com\/fr\/produit\/fr-ct-slideshow02\/\">\u00c9DITER CE MOD\u00c8LE <i class=\"fa-angle-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-title-short-description\" data-element_type=\"column\">Estate Large Agent<\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-short-description\" data-element_type=\"column\">Plan large pour promouvoir les espaces de vie de votre annonce immobili\u00e8re avec ce mod\u00e8le de vid\u00e9o qui fait d\u00e9filer les photos dans un format proche du cin\u00e9ma.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"display-one-template-box-choice\"><div class=\"elementor-column elementor-inner-column elementor-element bg-grey-gradient\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-widget\" data-element_type=\"widget\"><div class=\"elementor-widget-container\"><div class=\"elementor-row template-one-custom hover-cursor-pointer\" id=\"FRCSSlideshow03-template-one-custom\" style=\"position:relative;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CS-Slideshow03-1-width680.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"><div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div><script>$(\"#FRCSSlideshow03-template-one-custom\").click(function() {$(\"#FRCSSlideshow03-template-one-custom\").html(' <video id=\"video-FRCSSlideshow03\" poster=\"\/wp-content\/uploads\/src\/img\/FR-CS-Slideshow03-1.jpg\" controls> <source src=\"https:\/\/cdn.jwplayer.com\/videos\/YDb7Mm2u-ovXvHCqB.mp4\" type=\"video\/mp4\"> <\/video> <script> $(document).ready(function(){ var videoFRCSSlideshow03 = $(\"#video-FRCSSlideshow03\").get(0); videoFRCSSlideshow03.play(); videoFRCSSlideshow03.addEventListener(\"ended\", function(){ var imgContentSimVideo = `<img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CS-Slideshow03-1.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"> <div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div>`; $(\"#FRCSSlideshow03-template-one-custom\").html(imgContentSimVideo); }); }); <\\\/script>');});<\/script><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"fas fa-stopwatch picto-fontawesome-infos-template\"><\/i>30 sec.<\/div><\/div><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"far fa-images picto-fontawesome-infos-template\"><\/i>7<\/div><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element\" data-element_type=\"column\" style=\"text-align:center;\"><a class=\"button-choose-template-agency\" target=\"_self\" href=\"https:\/\/estatestudio.com\/fr\/produit\/fr-cs-slideshow03\/\">\u00c9DITER CE MOD\u00c8LE <i class=\"fa-angle-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-title-short-description\" data-element_type=\"column\">Estate Corner<\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-short-description\" data-element_type=\"column\">Dynamisez la pr\u00e9sentation de votre annonce immobili\u00e8re gr\u00e2ce \u00e0 l\u2019effet \u00ab pop-up \u00bb d\u2019apparition des photos de ce mod\u00e8le de vid\u00e9o.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"display-one-template-box-choice\"><div class=\"elementor-column elementor-inner-column elementor-element bg-grey-gradient\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-widget\" data-element_type=\"widget\"><div class=\"elementor-widget-container\"><div class=\"elementor-row template-one-custom hover-cursor-pointer\" id=\"FRCTSlideshow03-template-one-custom\" style=\"position:relative;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Slideshow03-1-width680.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"><div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div><script>$(\"#FRCTSlideshow03-template-one-custom\").click(function() {$(\"#FRCTSlideshow03-template-one-custom\").html(' <video id=\"video-FRCTSlideshow03\" poster=\"\/wp-content\/uploads\/src\/img\/FR-CT-Slideshow03-1.jpg\" controls> <source src=\"https:\/\/cdn.jwplayer.com\/videos\/hRNOJQIr-ovXvHCqB.mp4\" type=\"video\/mp4\"> <\/video> <script> $(document).ready(function(){ var videoFRCTSlideshow03 = $(\"#video-FRCTSlideshow03\").get(0); videoFRCTSlideshow03.play(); videoFRCTSlideshow03.addEventListener(\"ended\", function(){ var imgContentSimVideo = `<img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Slideshow03-1.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"> <div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div>`; $(\"#FRCTSlideshow03-template-one-custom\").html(imgContentSimVideo); }); }); <\\\/script>');});<\/script><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"fas fa-stopwatch picto-fontawesome-infos-template\"><\/i>30 sec.<\/div><\/div><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"far fa-images picto-fontawesome-infos-template\"><\/i>7<\/div><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element\" data-element_type=\"column\" style=\"text-align:center;\"><a class=\"button-choose-template-agency\" target=\"_self\" href=\"https:\/\/estatestudio.com\/fr\/produit\/fr-ct-slideshow03\/\">\u00c9DITER CE MOD\u00c8LE <i class=\"fa-angle-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-title-short-description\" data-element_type=\"column\">Estate Corner Agent<\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-short-description\" data-element_type=\"column\">Dynamisez la pr\u00e9sentation de votre annonce immobili\u00e8re gr\u00e2ce \u00e0 l\u2019effet \u00ab pop-up \u00bb d\u2019apparition des photos de ce mod\u00e8le de vid\u00e9o.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"display-one-template-box-choice\"><div class=\"elementor-column elementor-inner-column elementor-element bg-grey-gradient\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-widget\" data-element_type=\"widget\"><div class=\"elementor-widget-container\"><div class=\"elementor-row template-one-custom hover-cursor-pointer\" id=\"FRCSZoom04-template-one-custom\" style=\"position:relative;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CS-Zoom04-1-width680.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"><div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div><script>$(\"#FRCSZoom04-template-one-custom\").click(function() {$(\"#FRCSZoom04-template-one-custom\").html(' <video id=\"video-FRCSZoom04\" poster=\"\/wp-content\/uploads\/src\/img\/FR-CS-Zoom04-1.jpg\" controls> <source src=\"https:\/\/cdn.jwplayer.com\/videos\/wp0P2aZ5-ovXvHCqB.mp4\" type=\"video\/mp4\"> <\/video> <script> $(document).ready(function(){ var videoFRCSZoom04 = $(\"#video-FRCSZoom04\").get(0); videoFRCSZoom04.play(); videoFRCSZoom04.addEventListener(\"ended\", function(){ var imgContentSimVideo = `<img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CS-Zoom04-1.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"> <div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div>`; $(\"#FRCSZoom04-template-one-custom\").html(imgContentSimVideo); }); }); <\\\/script>');});<\/script><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"fas fa-stopwatch picto-fontawesome-infos-template\"><\/i>30 sec.<\/div><\/div><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"far fa-images picto-fontawesome-infos-template\"><\/i>6<\/div><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element\" data-element_type=\"column\" style=\"text-align:center;\"><a class=\"button-choose-template-agency\" target=\"_self\" href=\"https:\/\/estatestudio.com\/fr\/produit\/fr-cs-zoom04\/\">\u00c9DITER CE MOD\u00c8LE <i class=\"fa-angle-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-title-short-description\" data-element_type=\"column\">Estate Maps<\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-short-description\" data-element_type=\"column\">La localisation de votre bien est un de ses atouts majeurs ? Mettez-la en avant avec ce mod\u00e8le de vid\u00e9o qui d\u00e9marre par un effet de zoom sur la g\u00e9olocalisation du bien.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"display-one-template-box-choice\"><div class=\"elementor-column elementor-inner-column elementor-element bg-grey-gradient\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-widget\" data-element_type=\"widget\"><div class=\"elementor-widget-container\"><div class=\"elementor-row template-one-custom hover-cursor-pointer\" id=\"FRCTZoom04-template-one-custom\" style=\"position:relative;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Zoom04-1-width680.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"><div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div><script>$(\"#FRCTZoom04-template-one-custom\").click(function() {$(\"#FRCTZoom04-template-one-custom\").html(' <video id=\"video-FRCTZoom04\" poster=\"\/wp-content\/uploads\/src\/img\/FR-CT-Zoom04-1.jpg\" controls> <source src=\"https:\/\/cdn.jwplayer.com\/videos\/aOt6iGco-ovXvHCqB.mp4\" type=\"video\/mp4\"> <\/video> <script> $(document).ready(function(){ var videoFRCTZoom04 = $(\"#video-FRCTZoom04\").get(0); videoFRCTZoom04.play(); videoFRCTZoom04.addEventListener(\"ended\", function(){ var imgContentSimVideo = `<img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Zoom04-1.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"> <div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div>`; $(\"#FRCTZoom04-template-one-custom\").html(imgContentSimVideo); }); }); <\\\/script>');});<\/script><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"fas fa-stopwatch picto-fontawesome-infos-template\"><\/i>30 sec.<\/div><\/div><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"far fa-images picto-fontawesome-infos-template\"><\/i>6<\/div><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element\" data-element_type=\"column\" style=\"text-align:center;\"><a class=\"button-choose-template-agency\" target=\"_self\" href=\"https:\/\/estatestudio.com\/fr\/produit\/fr-ct-zoom04\/\">\u00c9DITER CE MOD\u00c8LE <i class=\"fa-angle-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-title-short-description\" data-element_type=\"column\">Estate Maps Agent<\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-short-description\" data-element_type=\"column\">La localisation de votre bien est un de ses atouts majeurs ? Mettez-la en avant avec ce mod\u00e8le de vid\u00e9o qui d\u00e9marre par un effet de zoom sur la g\u00e9olocalisation du bien.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"display-one-template-box-choice\"><div class=\"elementor-column elementor-inner-column elementor-element bg-grey-gradient\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-widget\" data-element_type=\"widget\"><div class=\"elementor-widget-container\"><div class=\"elementor-row template-one-custom hover-cursor-pointer\" id=\"FRCSSlideshow05-template-one-custom\" style=\"position:relative;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CS-Slideshow05-1-width680.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"><div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div><script>$(\"#FRCSSlideshow05-template-one-custom\").click(function() {$(\"#FRCSSlideshow05-template-one-custom\").html(' <video id=\"video-FRCSSlideshow05\" poster=\"\/wp-content\/uploads\/src\/img\/FR-CS-Slideshow05-1.jpg\" controls> <source src=\"https:\/\/cdn.jwplayer.com\/videos\/LQjkUSCa-ovXvHCqB.mp4\" type=\"video\/mp4\"> <\/video> <script> $(document).ready(function(){ var videoFRCSSlideshow05 = $(\"#video-FRCSSlideshow05\").get(0); videoFRCSSlideshow05.play(); videoFRCSSlideshow05.addEventListener(\"ended\", function(){ var imgContentSimVideo = `<img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CS-Slideshow05-1.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"> <div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div>`; $(\"#FRCSSlideshow05-template-one-custom\").html(imgContentSimVideo); }); }); <\\\/script>');});<\/script><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"fas fa-stopwatch picto-fontawesome-infos-template\"><\/i>30 sec.<\/div><\/div><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"far fa-images picto-fontawesome-infos-template\"><\/i>7<\/div><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element\" data-element_type=\"column\" style=\"text-align:center;\"><a class=\"button-choose-template-agency\" target=\"_self\" href=\"https:\/\/estatestudio.com\/fr\/produit\/fr-cs-slideshow05\/\">\u00c9DITER CE MOD\u00c8LE <i class=\"fa-angle-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-title-short-description\" data-element_type=\"column\">Estate Scan<\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-short-description\" data-element_type=\"column\">Balayez du regard chaque pi\u00e8ce gr\u00e2ce \u00e0 l\u2019effet de mouvement des photos de ce mod\u00e8le de vid\u00e9o, comme si vous y \u00e9tiez.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"display-one-template-box-choice\"><div class=\"elementor-column elementor-inner-column elementor-element bg-grey-gradient\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-widget\" data-element_type=\"widget\"><div class=\"elementor-widget-container\"><div class=\"elementor-row template-one-custom hover-cursor-pointer\" id=\"FRCTSlideshow05-template-one-custom\" style=\"position:relative;\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Slideshow05-1-width680.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"><div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div><script>$(\"#FRCTSlideshow05-template-one-custom\").click(function() {$(\"#FRCTSlideshow05-template-one-custom\").html(' <video id=\"video-FRCTSlideshow05\" poster=\"\/wp-content\/uploads\/src\/img\/FR-CT-Slideshow05-1.jpg\" controls> <source src=\"https:\/\/cdn.jwplayer.com\/videos\/sCCGQwkx-ovXvHCqB.mp4\" type=\"video\/mp4\"> <\/video> <script> $(document).ready(function(){ var videoFRCTSlideshow05 = $(\"#video-FRCTSlideshow05\").get(0); videoFRCTSlideshow05.play(); videoFRCTSlideshow05.addEventListener(\"ended\", function(){ var imgContentSimVideo = `<img decoding=\"async\" src=\"\/wp-content\/uploads\/src\/img\/FR-CT-Slideshow05-1.jpg\" alt=\"\" class=\"img-fluid\" style=\"width: 100%; margin: 0px auto; padding: 0px; border: 0px none;\"> <div class=\"simulate-play-button\"><i class=\"fas fa-play\"><\/i><\/div>`; $(\"#FRCTSlideshow05-template-one-custom\").html(imgContentSimVideo); }); }); <\\\/script>');});<\/script><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"fas fa-stopwatch picto-fontawesome-infos-template\"><\/i>30 sec.<\/div><\/div><div class=\"elementor-column elementor-inner-column elementor-element choose-template-time\" data-element_type=\"column\" style=\"width:50%;\"><div style=\"text-align:center; width:100%;\"><i class=\"far fa-images picto-fontawesome-infos-template\"><\/i>7<\/div><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element\" data-element_type=\"column\" style=\"text-align:center;\"><a class=\"button-choose-template-agency\" target=\"_self\" href=\"https:\/\/estatestudio.com\/fr\/produit\/fr-ct-slideshow05\/\">\u00c9DITER CE MOD\u00c8LE <i class=\"fa-angle-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-title-short-description\" data-element_type=\"column\">Estate Scan Agent<\/div><\/div><div class=\"elementor-row\"><div class=\"elementor-column elementor-element choose-template-short-description\" data-element_type=\"column\">Balayez du regard chaque pi\u00e8ce gr\u00e2ce \u00e0 l\u2019effet de mouvement des photos de ce mod\u00e8le de vid\u00e9o, comme si vous y \u00e9tiez.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9ez votre vid\u00e9o Quelques minutes pour choisir votre mod\u00e8le, ajouter vos photos, vos informations et votre vid\u00e9o immobili\u00e8re est pr\u00eate\u00a0! S\u00e9lectionnez votre r\u00e9seau Le r\u00e9seau que vous cherchez n&rsquo;est pas disponible ? Contactez-nous pour l&rsquo;ajouter \u00e0 EstateStudio OU Personnalisez un mod\u00e8le \u00e0 vos couleurs<\/p>\n","protected":false},"author":1,"featured_media":6933,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1843","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cr\u00e9er des vid\u00e9os immobili\u00e8res remarquables avec Estate Studio<\/title>\n<meta name=\"description\" content=\"Cr\u00e9ez en ligne votre vid\u00e9o immobili\u00e8re facilement et rapidement. Entrez les informations, ajoutez vos images et exportez votre vid\u00e9o !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cr\u00e9er des vid\u00e9os immobili\u00e8res remarquables avec Estate Studio\" \/>\n<meta property=\"og:description\" content=\"Cr\u00e9ez en ligne votre vid\u00e9o immobili\u00e8re facilement et rapidement. Entrez les informations, ajoutez vos images et exportez votre vid\u00e9o !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/\" \/>\n<meta property=\"og:site_name\" content=\"EstateStudio.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EstateStudiocom\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T07:38:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/06\/creer-video-EstateStudio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/selectionnez-votre-template\\\/\",\"url\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/selectionnez-votre-template\\\/\",\"name\":\"Cr\u00e9er des vid\u00e9os immobili\u00e8res remarquables avec Estate Studio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/selectionnez-votre-template\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/selectionnez-votre-template\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/estatestudio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/creer-video-EstateStudio.jpg\",\"datePublished\":\"2021-08-03T07:49:08+00:00\",\"dateModified\":\"2022-07-04T07:38:33+00:00\",\"description\":\"Cr\u00e9ez en ligne votre vid\u00e9o immobili\u00e8re facilement et rapidement. Entrez les informations, ajoutez vos images et exportez votre vid\u00e9o !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/selectionnez-votre-template\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/estatestudio.com\\\/fr\\\/selectionnez-votre-template\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/selectionnez-votre-template\\\/#primaryimage\",\"url\":\"https:\\\/\\\/estatestudio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/creer-video-EstateStudio.jpg\",\"contentUrl\":\"https:\\\/\\\/estatestudio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/creer-video-EstateStudio.jpg\",\"width\":1000,\"height\":563,\"caption\":\"creer une video avec Estate Studio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/selectionnez-votre-template\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e9lectionnez votre template\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/\",\"name\":\"EstateStudio.com\",\"description\":\"Cr\u00e9er vos vid\u00e9os immobili\u00e8res en ligne\",\"publisher\":{\"@id\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/#organization\",\"name\":\"EstateStudio.com\",\"url\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/estatestudio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/EstateStudio-1200.jpg\",\"contentUrl\":\"https:\\\/\\\/estatestudio.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/EstateStudio-1200.jpg\",\"width\":1200,\"height\":624,\"caption\":\"EstateStudio.com\"},\"image\":{\"@id\":\"https:\\\/\\\/estatestudio.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EstateStudiocom\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCcBwId4i8bRElU2sfx6EZPw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cr\u00e9er des vid\u00e9os immobili\u00e8res remarquables avec Estate Studio","description":"Cr\u00e9ez en ligne votre vid\u00e9o immobili\u00e8re facilement et rapidement. Entrez les informations, ajoutez vos images et exportez votre vid\u00e9o !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/","og_locale":"fr_FR","og_type":"article","og_title":"Cr\u00e9er des vid\u00e9os immobili\u00e8res remarquables avec Estate Studio","og_description":"Cr\u00e9ez en ligne votre vid\u00e9o immobili\u00e8re facilement et rapidement. Entrez les informations, ajoutez vos images et exportez votre vid\u00e9o !","og_url":"https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/","og_site_name":"EstateStudio.com","article_publisher":"https:\/\/www.facebook.com\/EstateStudiocom","article_modified_time":"2022-07-04T07:38:33+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/06\/creer-video-EstateStudio.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/","url":"https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/","name":"Cr\u00e9er des vid\u00e9os immobili\u00e8res remarquables avec Estate Studio","isPartOf":{"@id":"https:\/\/estatestudio.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/#primaryimage"},"image":{"@id":"https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/#primaryimage"},"thumbnailUrl":"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/06\/creer-video-EstateStudio.jpg","datePublished":"2021-08-03T07:49:08+00:00","dateModified":"2022-07-04T07:38:33+00:00","description":"Cr\u00e9ez en ligne votre vid\u00e9o immobili\u00e8re facilement et rapidement. Entrez les informations, ajoutez vos images et exportez votre vid\u00e9o !","breadcrumb":{"@id":"https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/#primaryimage","url":"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/06\/creer-video-EstateStudio.jpg","contentUrl":"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/06\/creer-video-EstateStudio.jpg","width":1000,"height":563,"caption":"creer une video avec Estate Studio"},{"@type":"BreadcrumbList","@id":"https:\/\/estatestudio.com\/fr\/selectionnez-votre-template\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/estatestudio.com\/fr\/"},{"@type":"ListItem","position":2,"name":"S\u00e9lectionnez votre template"}]},{"@type":"WebSite","@id":"https:\/\/estatestudio.com\/fr\/#website","url":"https:\/\/estatestudio.com\/fr\/","name":"EstateStudio.com","description":"Cr\u00e9er vos vid\u00e9os immobili\u00e8res en ligne","publisher":{"@id":"https:\/\/estatestudio.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/estatestudio.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/estatestudio.com\/fr\/#organization","name":"EstateStudio.com","url":"https:\/\/estatestudio.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/estatestudio.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/06\/EstateStudio-1200.jpg","contentUrl":"https:\/\/estatestudio.com\/wp-content\/uploads\/2022\/06\/EstateStudio-1200.jpg","width":1200,"height":624,"caption":"EstateStudio.com"},"image":{"@id":"https:\/\/estatestudio.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EstateStudiocom","https:\/\/www.youtube.com\/channel\/UCcBwId4i8bRElU2sfx6EZPw"]}]}},"_links":{"self":[{"href":"https:\/\/estatestudio.com\/fr\/wp-json\/wp\/v2\/pages\/1843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/estatestudio.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/estatestudio.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/estatestudio.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/estatestudio.com\/fr\/wp-json\/wp\/v2\/comments?post=1843"}],"version-history":[{"count":228,"href":"https:\/\/estatestudio.com\/fr\/wp-json\/wp\/v2\/pages\/1843\/revisions"}],"predecessor-version":[{"id":7649,"href":"https:\/\/estatestudio.com\/fr\/wp-json\/wp\/v2\/pages\/1843\/revisions\/7649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/estatestudio.com\/fr\/wp-json\/wp\/v2\/media\/6933"}],"wp:attachment":[{"href":"https:\/\/estatestudio.com\/fr\/wp-json\/wp\/v2\/media?parent=1843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}